{"id":1841,"date":"2020-02-10T22:20:12","date_gmt":"2020-02-10T21:20:12","guid":{"rendered":"https:\/\/race.build\/professionals-terms-of-sale\/"},"modified":"2025-01-21T12:58:03","modified_gmt":"2025-01-21T11:58:03","slug":"professionals-terms-sale","status":"publish","type":"page","link":"https:\/\/race.build\/en\/terms-sale\/professionals-terms-sale\/","title":{"rendered":"Professionals Terms of Sale"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1737460682688{margin-top: 70px !important;margin-bottom: 100px !important;}&#8221; css_params=&#8221;&#8221;]<\/p>\n<h2 class=\"uppercase\" style=\"text-align: center;\" data-fontsize=\"46\" data-lineheight=\"57\">TERMS OF SALE<\/h2>\n<h3 class=\"thin-font\" style=\"text-align: center;\" data-fontsize=\"26\" data-lineheight=\"33\">Professionals<\/h3>\n<p>&nbsp;<\/p>\n<p><b>\u00a0<\/b><\/p>\n<p><b>\u00a0<\/b><\/p>\n<p><b>1 OGGETTO E CONCLUSIONE DEL CONTRATTO<br \/>\n<\/b>Le presenti condizioni regolano la vendita diretta di beni e la fornitura di servizi da parte della RACE BUILD DI DANILO COLAONE (di seguito abbreviata come &#8220;RACE BUILD&#8221;), con sede in Via Rivoli 140, 10090 Villarbasse (TO), P.I. 12282990014, C.F. CLNDNL84M30H355R, iscritta al Registro delle Imprese della Camera di Commercio di TORINO, REA TO \u2013 1278396, annotata all&#8217;Albo Artigiani al n\u00b0 TO-379837, e-mail: <a href=\"mailto:info@race.build\">info@race.build<\/a>\u00a0mediante l\u2019applicazione contenuta nel sito\u00a0<a href=\"https:\/\/race.build\/\">www.race.build<\/a>, gli annunci pubblicati sui siti di terze parti quali ebay.it, kijiji.it e subito.it, nonch\u00e8 in tutti gli altri casi di vendita diretta effettuata a mezzo telefono, fax, e-mail, sms, whatsapp o altro.<br \/>\nIl Contratto di Vendita \u00e8 regolato dalle presenti Condizioni Generali, che costituiscono parte integrante e sostanziale del Contratto di Vendita, anche se non espressamente richiamate nell\u2019ordine e\/o nella conferma d\u2019ordine.<br \/>\nAl fine della conclusione del contratto \u00e8 necessaria l\u2019apposita iscrizione e registrazione del Cliente in formato elettronico nel database aziendale, la comunicazione di tutti i propri dati utili per la fatturazione e consegna dei beni oltre all\u2019accettazione della Privacy Policy e delle presenti condizioni.<br \/>\nIl Cliente ha l&#8217;onere di custodire e mantere riservate le proprie credenziali di accesso.<br \/>\nResta inteso che in nessun caso RACE BUILD potr\u00e0 essere ritenuta responsabile in caso di smarrimento, diffusione, furto o utilizzo non consentito da parte di terzi, a qualsivoglia titolo, delle credenziali di accesso dei Clienti.<br \/>\nLa conclusione del contratto \u00e8 in ogni caso subordinata all\u2019approvazione definitiva ed insindacabile della RACE BUILD la quale, in caso di mancata accettazione, dovr\u00e0 darne comunicazione al Cliente nelle forme che riterr\u00e0 pi\u00f9 opportune entro 20 giorni dalla ricezione dell\u2019ordine; in assenza di comunicazioni nel predetto termine il contratto si intende concluso.<br \/>\nLa RACE BUILD \u00e8 libera di non accettare gli ordini a suo insindacabile giudizio, ed esclude qualsiasi responsabilit\u00e0 contrattuale o extracontrattuale per danni diretti o indiretti eventualmente provocati dalla mancata accettazione, anche parziale di un ordine.<br \/>\nLa RACE BUILD assume gli obblighi di fornitura esclusivamente per i beni indicati nell\u2019ordine, nel solo caso di accettazione dello stesso.<br \/>\nEventuali modifiche richieste dal Cliente contestualmente o successivamente all\u2019invio della richiesta dovranno essere inoltrate per iscritto e saranno soggette a nuova accettazione della RACE BUILD che potr\u00e0, in ragione delle modifiche richieste, variare date di consegna e prezzi rispetto all\u2019ordine originario.<br \/>\nSi chiarisce che qualsiasi clausola o condizione inserita dal Cliente nell\u2019ordine, nella corrispondenza o altrove \u00e8 invalida ed inefficace se non specificamente accettata per iscritto dalla RACE BUILD.<br \/>\nLa conferma d\u2019ordine non pu\u00f2 in alcun modo essere interpretata come implicita accettazione di condizioni o clausole contenute nell\u2019ordine od altrove, se di esse non sia fatta espressa menzione nella conferma stessa e non sia inequivocabilmente espressa la volont\u00e0 della RACE BUILD di accettarle.<br \/>\nIl contratto di compravendita si perfeziona solo nel momento in cui la RACE BUILD avr\u00e0 dato conferma d\u2019acquisto nei termini sopra indicati per via telematica all\u2019indirizzo di posta elettronica indicato o, in mancanza, all\u2019indirizzo di residenza e\/o domicilio indicato o mediante fax.<br \/>\nLa conferma d\u2019ordine inviata dalla RACE BUILD conterr\u00e0 un riepilogo delle Condizioni Generali di Vendita, delle caratteristiche del bene ordinato e del relativo prezzo nonch\u00e9 dei mezzi di pagamento, dei mezzi di consegna e dei costi relativi a spedizione e consegna.<br \/>\nLa RACE BUILD non \u00e8 in alcun modo responsabile nel caso di errata comunicazione da parte del Cliente dei dati relativi all\u2019ordine (in via indicativa e non esaustiva della casistica: il nominativo e l\u2019indirizzo indicati per la spedizione del prodotto acquistato, le caratteristiche ed il quantitativo dei prodotti oggetto dell\u2019ordine).<br \/>\nIl Cliente alla sottoscrizione del presente contratto \u00e8 consapevole che gli eventuali beni usati oggetto di compravendita vengono venduti nello stato in cui si trovano, presentando i limiti prestazionali ed i difetti funzionali e\/o strutturali connessi al pregresso utilizzo del prodotto stesso ed \u00e8 in ragione di ci\u00f2 che il prezzo di vendita \u00e8 nettamente inferiore ad un bene del medesimo modello, marca e tipologia acquistato nuovo. Pertanto sono necessarie cure e manutenzioni previste dal costruttore.<br \/>\nIl Cliente \u00e8 altres\u00ec consapevole che l\u2019installazione del bene \u00e8 a proprio carico, ove non sia diversamente pattuito ed esplicitamente accettato in forma scritta dalla RACE BUILD.<br \/>\nCiascun Contratto di Vendita concluso fra RACE BUILD e il Cliente \u00e8 un separato ed autonomo negozio. Sono applicabili a ciascun Contratto di Vendita le Condizioni Generali vigenti al momento della trasmissione dell\u2019ordine.<br \/>\nLa RACE BUILD si riserva il diritto di sospendere o terminare in ogni momento la pubblicazione e l\u2019aggiornamento del catalogo dei beni in vendita, nonch\u00e9 di modificarlo in tutto o in parte a propria insindacabile discrezione e senza alcun obbligo di preavviso.<br \/>\nI marchi e gli altri segni distintivi riprodotti sul Catalogo online sono di propriet\u00e0 dei rispettivi titolari o della RACE BUILD che ne vieta la riproduzione anche parziale.<\/p>\n<p><b>2 PAGAMENTO<br \/>\n<\/b>Il Cliente \u00e8 tenuto al pagamento della merce secondo le modalit\u00e0 indicate nel modulo d\u2019ordine e non pu\u00f2 per alcuna ragione ed alcun titolo differire o sospendere i pagamenti pattuiti anche se fossero insorte delle contestazioni sull\u2019esecuzione o sull\u2019interpretazione del presente contratto.<br \/>\nQualora per qualsiasi motivo la consegna dovesse essere differita, la decorrenza dei pagamenti rester\u00e0 invariata.<br \/>\nLe fatture non contestate entro otto giorni dalla data di emissione si intendono definitivamente accettate.<br \/>\nPoich\u00e9 nessun Agente o Rappresentante ha il potere di incassare denaro per conto della RACE BUILD, l\u2019efficacia di eventuali pagamenti fatti a questi soggetti \u00e8 subordinata a preventiva ed esplicita autorizzazione della RACE BUILD.<br \/>\nIn caso di sospensione o interruzione dei pagamenti il Cliente sar\u00e0 considerato ad ogni effetto di legge come inadempiente facendo salvo il diritto alla risoluzione del contratto e contestuale richiesta di risarcimento del danno.<br \/>\nIn ogni caso, qualora fosse pattuito il pagamento in pi\u00f9 rate, il mancato versamento dell\u2019importo pattuito o di una sola rata convenuta implica per il Cliente la decadenza dal beneficio del termine e la RACE BUILD avr\u00e0 diritto di pretendere il pagamento del residuo in un\u2019unica soluzione.<br \/>\nIn caso di ritardo nel pagamento si applicheranno gli interessi moratori ex D.lgs. n. 231\/2002.<br \/>\nLa RACE BUILD mette a disposizione dei propri Clienti le seguenti modalit\u00e0 di pagamento:<\/p>\n<p>1. Bonifico Bancario;<br \/>\n2. Carta di Debito e Credito;<br \/>\n3. Bollettino Freccia.<\/p>\n<p>In ogni caso il pagamento deve essere eseguito dal Cliente contestualmente all\u2019ordine.<br \/>\nLa RACE BUILD si riserva il diritto di proporre, a proprio insindacabile giudizio, delle forme alternative di pagamento, quali ad esempio il pagamento in contrassegno. Per utilizzare questo metodo \u00e8 richiesto il versamento di un acconto contestualmente all\u2019ordine; il saldo avverr\u00e0 esclusivamente in contanti alla consegna con corriere espresso.<\/p>\n<p>\u00c8 facolt\u00e0 del Cliente chiedere in fase di ordinazione di ritirare i beni franco magazzino del venditore; in questo caso \u00e8 richiesto il pagamento anticipato a mezzo di una delle tre modalit\u00e0 sopra esposte, oppure in contanti o carta di debito\/credito presso la sede operativa della Societ\u00e0.<br \/>\nLa RACE BUILD, in quest&#8217;ultimo caso, si riserva il diritto di proporre al Cliente, a proprio insindacabile giudizio, di versare solo un acconto contestualmente all\u2019ordine, ed effettuare il saldo al ritiro in sede, esclusivamente in contanti o con carta di debito\/credito.<\/p>\n<p>RACE BUILD utilizza strumenti terzi per l&#8217;elaborazione dei pagamenti elettronici e non entra in alcun modo in contatto con dati di pagamento \u2013 come quelli relativi alla carta di credito \u2013 forniti.<br \/>\nQualora il titolare di ciascuno di tali strumenti terzi dovesse rifiutare l&#8217;autorizzazione al pagamento, la RACE BUILD non potr\u00e0 fornire il Servizio e non sar\u00e0 responsabile per un eventuale ritardo o per una mancata consegna.<\/p>\n<p><b>3 CLAUSOLA RISOLUTIVA ESPRESSA<br \/>\n<\/b>In caso di ritardo o mancanza dei pagamenti nei termini e nelle forme pattuite la RACE BUILD si riserva il diritto all\u2019immediata azione legale per il recupero del credito, gravato dagli interessi di mora come sopra stabiliti e dalle spese legali.<br \/>\nIl mancato pagamento alle scadenze indicate o di una sola rata eventualmente pattuita dar\u00e0 diritto alla RACE BUILD di risolvere il presente contratto ai sensi dell\u2019art. 1456 c.c..<br \/>\nLa risoluzione opera di diritto quando RACE BUILD comunica per via telematica all\u2019indirizzo di posta elettronica indicato nel modulo d\u2019ordine o, in mancanza all\u2019indirizzo di residenza \/domicilio che intende avvalersi della presente clausola.<br \/>\nAnche nel caso in cui il recesso previsto per legge non avvenga secondo le modalit\u00e0 indicate, si applicheranno le norme di cui all\u2019art. 1453 e seguenti del Codice Civile che comportano l\u2019obbligo a carico del Cliente del pagamento del prezzo pattuito per il bene fornito, fatto salvo il diritto alla risoluzione del contratto, oltre in ogni caso al risarcimento del danno patito dalla RACE BUILD.<\/p>\n<p><b>4 SPEDIZIONE E CONSEGNA<br \/>\n<\/b>La RACE BUILD provveder\u00e0 ad imballare il bene in modo da garantirne l\u2019integrit\u00e0 ed invier\u00e0 lo stesso esclusivamente all\u2019indirizzo indicato dal Cliente.<br \/>\nIl trasporto si intende a rischio e pericolo del Cliente anche se caricato su automezzi della RACE BUILD, pertanto, cessa ogni responsabilit\u00e0 della stessa con la consegna al vettore.<br \/>\nIl trasporto effettuato tramite corriere viene offerto con le modalit\u00e0 CPT Incoterms@2010.<br \/>\nLa sottoscrizione da parte del Cliente del documento di trasporto del vettore comporta piena accettazione della merce consegnata per quanto attiene, ad esempio, agli imballi, al numero dei colli ricevuti, alla corrispondenza fra prodotti ordinati e prodotti consegnati, all\u2019integrit\u00e0 ed alle caratteristiche esteriori dei prodotti.<br \/>\nIl Cliente \u00e8 tenuto alla verifica immediata dello stato della merce consegnata e dei relativi imballi, nonch\u00e9 che corrisponda effettivamente ai beni richiesti, elevando, se nel caso, immediata osservazione scritta sul Documento di Trasporto alla voce: \u201cANNOTAZIONI ed accettando \u201cCON RISERVA\u201d la merce, apponendo tale dicitura sulla ricevuta del corriere contestualmente alla firma per accettazione.<br \/>\nPur in presenza di imballo integro, i beni dovranno essere diligentemente verificati dal Cliente, ed eventuali vizi e non conformit\u00e0 apparenti (e quindi oggettivamente riconoscibili con l\u2019uso della normale diligenza) dei beni dovranno a pena di decadenza della garanzia essere denunziati per iscritto alla RACE BUILD, entro e non oltre 8 (otto) giorni di calendario dalla data di consegna.<br \/>\nI termini di spedizione sono da considerarsi meramente indicativi e non tassativi. La decorrenza avr\u00e0 inizio dal giorno in cui saranno pervenuti alla RACE BUILD tutti i dati necessari per l\u2019espletamento della fornitura e comunque dopo l\u2019avvenuto invio del modulo informatico di accettazione.<br \/>\nLa RACE BUILD non risponde per eventuali ritardi dovuti a causa di forza maggiore quali, a titolo meramente esemplificativo ma non esaustivo, incidenti, incendi, esplosioni, scioperi, serrate, terremoti, disastri, alluvioni, sommosse, leggi, regolamenti ed ordini promanati da autorit\u00e0 statali, ed altri eventi di difficile o impossibile previsione che impedissero, in tutto o in parte, di adempiere nei tempi o nei modi concordati ed ogni altro caso di ritardo non attribuibile a suo dolo o colpa grave.<br \/>\nI termini di spedizione sono interrotti nel periodo che va dall\u20191 al 31 agosto e dal 15 dicembre al 6 gennaio dell\u2019anno successivo.<br \/>\nIl Cliente non pu\u00f2 in nessun caso esigere danni o avanzare altre pretese per il ritardo nelle consegne, n\u00e9 chiedere la risoluzione del contratto.<br \/>\nIn ogni caso, qualora il Cliente non voglia ricevere quanto acquistato, la RACE BUILD si riserva il diritto di chiedere quanto versato per le spese di spedizione sostenute.<\/p>\n<p><b>5 GARANZIA<br \/>\n<\/b>Il Cliente alla sottoscrizione del presente contratto \u00e8 consapevole che gli eventuali beni usati oggetto di compravendita vengono venduti nello stato in cui si trovano, presentando i limiti prestazionali ed i difetti funzionali e\/o strutturali connessi al pregresso utilizzo del prodotto stesso ed \u00e8 in ragione di ci\u00f2 che il prezzo di vendita \u00e8 nettamente inferiore ad un bene del medesimo modello, marca e tipologia acquistato nuovo. Pertanto sono necessarie cure e manutenzioni previste dal costruttore.<br \/>\nLe parti concordano che la fornitura del materiale usato sia garantita attraverso la formula della c.d. Garanzia per i vizi della cosa venduta, ai sensi dell\u2019 art.1490 del Codice Civile.<br \/>\nLa garanzia decade qualora il cliente, senza la preventiva autorizzazione scritta della RACE BUILD, abbia operato sullo stesso direttamente e\/o richiesto a terzi montaggi e\/o smontaggi e\/o riparazioni e\/o sostituzioni di parti.<br \/>\nIn caso di validit\u00e0 della garanzia il Cliente avr\u00e0 diritto alla sola sostituzione dei prodotti danneggiati solo ed esclusivamente dietro restituzione degli stessi nelle medesime condizioni in cui sono stati spediti, essendo escluso il diritto del Cliente al risarcimento di qualsivoglia danno, anche ulteriore.<br \/>\nQualora il Cliente decidesse di utilizzare un vettore per consegnare il prodotto a RACE BUILD per le opportune verifiche, il primo dovr\u00e0 sostenerne i costi e garantirne il perfetto imballo, assumendo ogni responsabilit\u00e0 in caso di rottura o smarrimento del bene durante il trasporto.<br \/>\nLa garanzia non prevede nessun tipo di rimborso per spese di manodopera e materiali di consumo e\/o di qualsiasi altra spesa accessoria.<br \/>\nL\u2019 eventuale risarcimento di qualsiasi danno al Cliente non potr\u00e0 comunque superare la quota di valore del prodotto difettoso venduto.<br \/>\nSalvo il caso di dolo o di colpa grave del venditore, lo stesso non sar\u00e0 responsabile nei confronti del Cliente per qualsiasi danno o perdita subiti dal Cliente in seguito o come conseguenza di qualsiasi azione di garanzia da parte di un consumatore finale dei Prodotti o di una azione di regresso da parte di un diverso intermediario della catena contrattuale distributiva o di un qualsiasi altro intermediario. A tale scopo il Cliente rinuncia a qualsiasi azione o diritto di regresso verso il venditore. (rif. art. 131 del Codice del Consumo).<br \/>\nLa garanzia offerta non opera quando:<\/p>\n<ul>\n<li>i documenti allegati a dimostrazione dell\u2019acquisto presso la RACE BUILD appaiano alterati o illeggibili; la richiesta verr\u00e0 evasa solo se nel pacco rientrato saranno presenti fattura e modulo di conferma ordine;<\/li>\n<li>codici, segni propri di riconoscimento o numeri di matricola del prodotto risultino diversi da quelli del bene ceduto al cliente da RACE BUILD, oppure risultino alterati, cancellati, rimossi o resi illeggibili;<\/li>\n<li>il prodotto non sia stato installato da operatori professionali, specifici ed autorizzati;<\/li>\n<li>il prodotto sia stato aperto, smontato, riparato, modificato o manomesso da personale non autorizzato prima che la RACE BUILD abbia potuto procedere alla verifica tecnica;<\/li>\n<li>l\u2019esito della verifica tecnica rilevi che il vizio del prodotto discende da negligenza o trascuratezza nell\u2019installazione e\/o uso e\/o nella manutenzione;<\/li>\n<li>il prodotto, ritenuto difettoso dal Cliente e restituito alla RACE BUILD, pervenga alla sede della RACE BUILD privo di idoneo imballo;<\/li>\n<li>in ogni caso in cui non possano farsi risalire a difetti di produzione, fabbricazione, confezione o conservazione del prodotto.<\/li>\n<\/ul>\n<p><b>6 RISERVA DI PROPRIETA\u2019<br \/>\n<\/b>RACE BUILD conserva la propriet\u00e0 dei beni consegnati fino all\u2019integrale pagamento ai sensi degli art. 1523 e ss. c.c..<br \/>\nIn caso di risoluzione del contratto per inadempimento del Cliente, quanto versato rimarr\u00e0 alla RACE BUILD a titolo di compenso del godimento intercorso e di indennizzo, salvo il risarcimento del maggior danno.<br \/>\nResta ferma la liberazione per RACE BUILD da ogni rischio, onere e responsabilit\u00e0 relativi ai prodotti con la consegna degli stessi al vettore.<\/p>\n<p><b>7 COMPENSAZIONI<br \/>\n<\/b>Il Cliente rinuncia fin d\u2019ora a compensazioni fra l\u2019obbligo di pagamento ed eventuali pretese creditorie di qualsiasi natura.<\/p>\n<p><b>8 VENDITA ESCLUSIVA<br \/>\n<\/b>Le presenti Condizioni Generali disciplinano la vendita dei prodotti commercializzati da RACE BUILD esclusivamente verso Clienti che agiscono nell\u2019ambito della propria attivit\u00e0 imprenditoriale, commerciale, artigianale o professionale.<br \/>\nIl Cliente accettando le presenti condizioni dichiara e riconosce pertanto che l\u2019acquisto dei prodotti inerisce all\u2019attivit\u00e0 imprenditoriale, commerciale, artigianale o professionale svolta, con conseguente inapplicabilit\u00e0 al contratto di vendita del D.lgs. n. 206\/2005, del D.lgs. n. 185\/1999 e di altre disposizioni di legge concernenti la tutela del consumatore.<br \/>\nLa RACE BUILD informa che ai sensi del D.Lgs. 209\/2003 e della legge 5 Febbraio 1992, n. 122 e successive modifiche i ricambi attinenti alla sicurezza del veicolo, quali (in via esemplificativa e non esaustiva):<\/p>\n<p>impianto freni; servofreno; pompa\/cilindro freni; dischi\/tamburi; pinza completa; disco portafreni; tubazioni flessibili\/rigide; pedaliera completa; caveria freno a mano; leva freno a mano; sterzo; albero superiore e inferiore snodato; tiranteria lato cremagliera\/ruote; tubazioni idroguida; organi servosterzo; sospensione anteriore\/posteriore; montanti\/mozzi\/fusi con relativi cuscinetti; bracci oscillanti; perni a sfera; puntoni\/barre stabilizzatrici\/aste longitudinali; traverse e telai; ammortizzatori; trasmissione; semiassi; tubazioni impianto alimentazione; pompa benzina esterna; sistemi di ritenuta per sicurezza passiva (cinture, pretensionatori, air bag)<\/p>\n<p>possono essere venduti esclusivamente agli iscritti alle imprese esercenti attivit\u00e0 di autoriparazione.<br \/>\nPertanto, secondo tale legge rientrano nell\u2019attivit\u00e0 di autoriparazione le attivit\u00e0 di:<\/p>\n<p>1. Meccanica e motoristica;<br \/>\n2. Carrozzeria;<br \/>\n3. Elettrauto;<br \/>\n4. Gommista.<\/p>\n<p>Per tale motivo la RACE BUILD si riserva il diritto di evadere gli ordini che presentino ricambi facenti parte delle categorie sopra elencate o qualora a suo insindacabile giudizio ritenga ne possano fare parte.<\/p>\n<p><strong>9 INEFFICACIA E NULLITA&#8217; PARZIALE<br \/>\n<\/strong>Qualora una qualsiasi clausola delle presenti Condizioni di Vendita dovesse risultare nulla, non valida o inefficace, la suddetta clausola sar\u00e0 eliminata mentre le restanti clausole non saranno da ci\u00f2 condizionate e rimarranno pienamente efficaci.<\/p>\n<p><b>10 LEGGE APPLICABILE E FORO COMPETENTE<br \/>\n<\/b>Le sopra specificate Condizioni Generali di Vendita sono regolate in via esclusiva dalla legge italiana a prescindere dal luogo in cui l\u2019acquirente si trovi o l\u2019ordine debba essere inviato.<br \/>\nPer ogni eventuale controversia o contestazione nascente dal presente contratto sar\u00e0 competente in via esclusiva l\u2019autorit\u00e0 giudiziaria di Torino, tale competenza non potr\u00e0 essere derogata per ragione alcuna di continenza, esecuzione, accessoriet\u00e0 o connessioni di lite.<\/p>\n<p><b>11 INFORMATIVA SUL TRATTAMENTO DEI DATI PERSONALI<br \/>\n<\/b>Per informazioni sull&#8217;utilizzo dei dati personali, i Clienti devono fare riferimento alla\u00a0<a href=\"https:\/\/race.build\/en\/privacy-policy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Privacy Policy<\/a>.<\/p>\n<h3 style=\"text-align: center;\" data-fontsize=\"26\" data-lineheight=\"33\">IMPORTANTE<\/h3>\n<p style=\"text-align: center;\">Gli ordini sono impegnativi.<br \/>\nIn caso di merce gi\u00e0 spedita e rifiuto al corriere addetto o di mancata consegna per responsabilit\u00e0 diretta del cliente, verr\u00e0 emessa fattura per l\u2019intero costo della spedizione nonch\u00e9 il costo della resa al mittente, da saldare secondo le modalit\u00e0 che vi verranno comunicate.<br \/>\nAl Cliente verr\u00e0 esplicitamente richiesto di pagare la cifra entro un determinato periodo; in caso di mancato pagamento, la controversia verr\u00e0 affidata al nostro servizio legale.<\/p>\n<p style=\"text-align: center;\">La RACE BUILD non si ritiene responsabile per l\u2019acquisto di materiale in contrasto con particolari normative vigenti nei singoli Paesi che ne restringano la vendita.<\/p>\n<p style=\"text-align: center;\">Gli acquisti di beni e di servizi effettuati attraverso la piattaforma di vendita online\u00a0<a href=\"https:\/\/race.build\/\">www.race.build<\/a>, gli store della ditta su ebay.it, kijiji.it e subito.it, nonch\u00e8 in tutti gli altri casi di compravendita diretta effettuata a mezzo telefono, fax, email, sms, whatsapp o altro, sono regolati dalle presenti Condizioni di Vendita pubblicate sul sito\u00a0<a href=\"https:\/\/race.build\/\">www.race.build<\/a>.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1737460682688{margin-top: 70px !important;margin-bottom: 100px !important;}&#8221; css_params=&#8221;&#8221;] TERMS OF SALE Professionals &nbsp; \u00a0 \u00a0 1 OGGETTO E CONCLUSIONE DEL CONTRATTO Le presenti condizioni regolano la vendita diretta di beni e la fornitura di servizi da parte della RACE BUILD DI DANILO COLAONE (di seguito abbreviata come &#8220;RACE BUILD&#8221;), con sede in Via Rivoli 140, 10090 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1888,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"class_list":["post-1841","page","type-page","status-publish","hentry"],"yoast_head":"\n<title>Professionals Terms of Sale - #RACEBUILD<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Professionals Terms of Sale - #RACEBUILD\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1737460682688{margin-top: 70px !important;margin-bottom: 100px !important;}&#8221; css_params=&#8221;&#8221;] TERMS OF SALE Professionals &nbsp; \u00a0 \u00a0 1 OGGETTO E CONCLUSIONE DEL CONTRATTO Le presenti condizioni regolano la vendita diretta di beni e la fornitura di servizi da parte della RACE BUILD DI DANILO COLAONE (di seguito abbreviata come &#8220;RACE BUILD&#8221;), con sede in Via Rivoli 140, 10090 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/race.build\/en\/terms-sale\/professionals-terms-sale\/\" \/>\n<meta property=\"og:site_name\" content=\"#RACEBUILD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/racebuild1\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-21T11:58:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/race.build\/media\/2020\/02\/LG_RB_vre.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"197\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@race_build\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/race.build\/en\/terms-sale\/professionals-terms-sale\/\",\"url\":\"https:\/\/race.build\/en\/terms-sale\/professionals-terms-sale\/\",\"name\":\"Professionals Terms of Sale - #RACEBUILD\",\"isPartOf\":{\"@id\":\"https:\/\/race.build\/en\/#website\"},\"datePublished\":\"2020-02-10T21:20:12+00:00\",\"dateModified\":\"2025-01-21T11:58:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/race.build\/en\/terms-sale\/professionals-terms-sale\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/race.build\/en\/terms-sale\/professionals-terms-sale\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/race.build\/en\/terms-sale\/professionals-terms-sale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/race.build\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terms of sale\",\"item\":\"https:\/\/race.build\/en\/terms-sale\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Professionals Terms of Sale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/race.build\/en\/#website\",\"url\":\"https:\/\/race.build\/en\/\",\"name\":\"#RACEBUILD\",\"description\":\"Motorsport Standalone ECUs and racing instruments, installation, calibration, dyno tuning, MIL-SPEC Wiring Harnesses, prototyping and manifacturing of special parts (steel, alloy and plastics - 3D printing)\",\"publisher\":{\"@id\":\"https:\/\/race.build\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/race.build\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/race.build\/en\/#organization\",\"name\":\"RACE BUILD\",\"url\":\"https:\/\/race.build\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/race.build\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/race.build\/media\/2020\/02\/LG_RB_vre.png\",\"contentUrl\":\"https:\/\/race.build\/media\/2020\/02\/LG_RB_vre.png\",\"width\":400,\"height\":197,\"caption\":\"RACE BUILD\"},\"image\":{\"@id\":\"https:\/\/race.build\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/racebuild1\",\"https:\/\/x.com\/race_build\",\"https:\/\/www.instagram.com\/race.build\",\"https:\/\/www.youtube.com\/channel\/UCoHfLCcHSI_g5RT-3wHnlOQ\"]}]}<\/script>\n","yoast_head_json":{"title":"Professionals Terms of Sale - #RACEBUILD","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"en_US","og_type":"article","og_title":"Professionals Terms of Sale - #RACEBUILD","og_description":"[vc_row][vc_column][vc_column_text css=&#8221;.vc_custom_1737460682688{margin-top: 70px !important;margin-bottom: 100px !important;}&#8221; css_params=&#8221;&#8221;] TERMS OF SALE Professionals &nbsp; \u00a0 \u00a0 1 OGGETTO E CONCLUSIONE DEL CONTRATTO Le presenti condizioni regolano la vendita diretta di beni e la fornitura di servizi da parte della RACE BUILD DI DANILO COLAONE (di seguito abbreviata come &#8220;RACE BUILD&#8221;), con sede in Via Rivoli 140, 10090 [&hellip;]","og_url":"https:\/\/race.build\/en\/terms-sale\/professionals-terms-sale\/","og_site_name":"#RACEBUILD","article_publisher":"https:\/\/www.facebook.com\/racebuild1","article_modified_time":"2025-01-21T11:58:03+00:00","og_image":[{"width":400,"height":197,"url":"https:\/\/race.build\/media\/2020\/02\/LG_RB_vre.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@race_build","twitter_misc":{"Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/race.build\/en\/terms-sale\/professionals-terms-sale\/","url":"https:\/\/race.build\/en\/terms-sale\/professionals-terms-sale\/","name":"Professionals Terms of Sale - #RACEBUILD","isPartOf":{"@id":"https:\/\/race.build\/en\/#website"},"datePublished":"2020-02-10T21:20:12+00:00","dateModified":"2025-01-21T11:58:03+00:00","breadcrumb":{"@id":"https:\/\/race.build\/en\/terms-sale\/professionals-terms-sale\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/race.build\/en\/terms-sale\/professionals-terms-sale\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/race.build\/en\/terms-sale\/professionals-terms-sale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/race.build\/en\/"},{"@type":"ListItem","position":2,"name":"Terms of sale","item":"https:\/\/race.build\/en\/terms-sale\/"},{"@type":"ListItem","position":3,"name":"Professionals Terms of Sale"}]},{"@type":"WebSite","@id":"https:\/\/race.build\/en\/#website","url":"https:\/\/race.build\/en\/","name":"#RACEBUILD","description":"Motorsport Standalone ECUs and racing instruments, installation, calibration, dyno tuning, MIL-SPEC Wiring Harnesses, prototyping and manifacturing of special parts (steel, alloy and plastics - 3D printing)","publisher":{"@id":"https:\/\/race.build\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/race.build\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/race.build\/en\/#organization","name":"RACE BUILD","url":"https:\/\/race.build\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/race.build\/en\/#\/schema\/logo\/image\/","url":"https:\/\/race.build\/media\/2020\/02\/LG_RB_vre.png","contentUrl":"https:\/\/race.build\/media\/2020\/02\/LG_RB_vre.png","width":400,"height":197,"caption":"RACE BUILD"},"image":{"@id":"https:\/\/race.build\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/racebuild1","https:\/\/x.com\/race_build","https:\/\/www.instagram.com\/race.build","https:\/\/www.youtube.com\/channel\/UCoHfLCcHSI_g5RT-3wHnlOQ"]}]}},"_links":{"self":[{"href":"https:\/\/race.build\/en\/wp-json\/wp\/v2\/pages\/1841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/race.build\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/race.build\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/race.build\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/race.build\/en\/wp-json\/wp\/v2\/comments?post=1841"}],"version-history":[{"count":0,"href":"https:\/\/race.build\/en\/wp-json\/wp\/v2\/pages\/1841\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/race.build\/en\/wp-json\/wp\/v2\/pages\/1888"}],"wp:attachment":[{"href":"https:\/\/race.build\/en\/wp-json\/wp\/v2\/media?parent=1841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}